{"id":7656,"date":"2024-06-20T15:00:27","date_gmt":"2024-06-20T13:00:27","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7656"},"modified":"2024-06-20T15:00:27","modified_gmt":"2024-06-20T13:00:27","slug":"toyota-motor-de-hidrogeno-253-grados","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/toyota-motor-de-hidrogeno-253-grados\/7656\/","title":{"rendered":"Toyota ten\u00eda el primer motor de hidr\u00f3geno, ahora han presentado algo mejor: est\u00e1 a 253 grados bajo cero"},"content":{"rendered":"<p>Toyota se encuentra entre las<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-de-hidrogeno-cientificos\/6881\/\"> f\u00e1bricas automotrices pioneras en la utilizaci\u00f3n de las energ\u00edas renovables<\/a> en su l\u00ednea de veh\u00edculos de alta gama, urbanos y tambi\u00e9n ha probado su eficiencia en las competencias. En 2023 ya hab\u00eda presentado en carrera<strong> su primer prototipo con motor de hidr\u00f3geno<\/strong> con algunas deficiencias y para este a\u00f1o optimiz\u00f3 su modelo logrando mayor eficiencia en las pistas.<\/p>\n<h2>\u00bfC\u00f3mo es este nuevo motor de hidr\u00f3geno de Toyota?<\/h2>\n<p>En el marco de la \u00faltima competencia de las 24 Horas de Napac Fuji SUPER TEC llevada a cabo entre los d\u00edas 24 al 26 de mayo en el Circuito de Fuji en Jap\u00f3n, hizo su debut en las pruebas de las Super Taikyu Series el motor de hidr\u00f3geno l\u00edquido, mejorando la \u00faltima presentaci\u00f3n del a\u00f1o anterior.<\/p>\n<p><strong>El nuevo Toyota GR Corolla H2<\/strong> de competici\u00f3n presentado este a\u00f1o optimiz\u00f3 la tecnolog\u00eda del motor de hidr\u00f3geno a trav\u00e9s de una bomba alternativa que introduce un nuevo sistema de manivela de doble accionamiento que optimiza la resistencia de la bomba.<\/p>\n<p>Es importante tener en cuenta el desaf\u00edo que genera un motor de hidr\u00f3geno l\u00edquido en una pista de competencia por la exigencia que conlleva<strong> mantener el combustible a temperaturas extremadamente bajas de por lo menos -253 grados Celsius<\/strong> durante su llenado y almacenamiento.<\/p>\n<p>Aun as\u00ed, este nuevo modelo demostr\u00f3 que puede duplicar su capacidad y autonom\u00eda y proporcionar una densidad energ\u00e9tica mayor utilizando los mismos tiempos de recarga del tanque.<\/p>\n<h2>\u00bfC\u00f3mo funciona el nuevo motor?<\/h2>\n<p>Una de las deficiencias que presentaba el modelo 2023 se encontraba en los cojinetes del eje y en los engranajes situados en un extremo de la biela, que al elevarse la temperatura por efecto del aceite ten\u00edan que soportar cargas desiguales, lo que provocaba un desgaste acelerado del motor.<\/p>\n<p>La novedad de este<strong> nuevo modelo con manivela de doble accionamiento<\/strong> es que nivela la presi\u00f3n del par motor en ambos extremos del cig\u00fce\u00f1al, logrando un movimiento equilibrado del pist\u00f3n de refuerzo, lo que aumenta la durabilidad al motor.<\/p>\n<p>Adicionalmente, se han aplicado otras modificaciones en relaci\u00f3n a la l\u00ednea anterior, como el dise\u00f1o ovalado del tanque de hidr\u00f3geno l\u00edquido, dejando atr\u00e1s su forma cil\u00edndrica. Esta innovaci\u00f3n ha contribuido en duplicar el volumen del contenido almacenado.<\/p>\n<p>Por lo tanto, al aumentar los niveles de hidr\u00f3geno l\u00edquido acumulados,<strong> eleva tambi\u00e9n la autonom\u00eda del veh\u00edculo<\/strong> comparado con los tanques de hidr\u00f3geno gaseoso comprimido de 700 bares utilizados hasta el a\u00f1o 2022.<\/p>\n<h2>Ventajas sostenibles del nuevo modelo de motor de hidr\u00f3geno de Toyota<\/h2>\n<p>La tecnolog\u00eda aplicada en este desarrollo ha perfeccionado el sistema de captura de carbono con respecto al modelo anterior, actuando en el sistema de entrada de aire en vez de a nivel del escape. En este sentido, el carbono se almacena en un tanque adicional que en la edici\u00f3n 2023 era separado manualmente.<\/p>\n<p>Sin embargo, en esta l\u00ednea actual introduce un mecanismo que <strong>activa la funci\u00f3n de separaci\u00f3n de carbono del aires autom\u00e1ticamente<\/strong>, girando un filtro de absorci\u00f3n de carbono mientras el veh\u00edculo se encuentra en funcionamiento.<\/p>\n<p>Con todas estas modificaciones, la bomba de combustible que hab\u00eda tenido que ser reemplazada dos veces en la carrera anterior con la p\u00e9rdida de tiempo que esa situaci\u00f3n ha implicado, este a\u00f1o ha evolucionado con mayor fiabilidad y manteniendo las temperaturas en sus rigurosas marcas.<\/p>\n<p>De esta manera, la nueva optimizaci\u00f3n del motor de hidr\u00f3geno<strong> ha logrado un prototipo m\u00e1s competitivo y \u00e1gil<\/strong> con menores paradas en los boxes y redujo los tiempos en vueltas por la reducci\u00f3n de peso alcanzada en m\u00e1s de 50 kg con respecto al motor anterior.<\/p>\n<p>El \u00e9xito alcanzado en las pistas este a\u00f1o augura para Toyota la factibilidad de lanzar un motor de hidr\u00f3geno competitivo y eficiente para las l\u00edneas urbanas, lo que marca <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/motor-de-hidrogeno-en-gas\/6638\/\">un nuevo hito para la movilidad sostenible<\/a> en el mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toyota se encuentra entre las f\u00e1bricas automotrices pioneras en la utilizaci\u00f3n de las energ\u00edas renovables en su l\u00ednea de veh\u00edculos &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Toyota ten\u00eda el primer motor de hidr\u00f3geno, ahora han presentado algo mejor: est\u00e1 a 253 grados bajo cero\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/toyota-motor-de-hidrogeno-253-grados\/7656\/#more-7656\" aria-label=\"Leer m\u00e1s sobre Toyota ten\u00eda el primer motor de hidr\u00f3geno, ahora han presentado algo mejor: est\u00e1 a 253 grados bajo cero\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":7695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7656"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7695"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}