{"id":7716,"date":"2024-06-21T14:30:11","date_gmt":"2024-06-21T12:30:11","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7716"},"modified":"2024-06-21T14:30:11","modified_gmt":"2024-06-21T12:30:11","slug":"turbina-eolica-purifica-aire","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/turbina-eolica-purifica-aire\/7716\/","title":{"rendered":"Esta turbina e\u00f3lica genera electricidad en casa y purifica el aire: es como si tuvieras 300 \u00e1rboles"},"content":{"rendered":"<p>En busca de soluciones sostenibles adaptables en \u00e1reas urbanas, se han desarrollado proyectos de<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/persianas-fotovoltaicas-paneles\/7017\/\"> generaci\u00f3n de energ\u00eda renovable como las placas fotovoltaicas en persianas<\/a> o el aerogenerador para tu casa. Ahora, una empresa da un paso m\u00e1s all\u00e1 y combina dos m\u00e9todos de recolecci\u00f3n y producci\u00f3n en un solo dispositivo a partir de<strong> una turbina e\u00f3lica que purifica el aire<\/strong>.<\/p>\n<h2>La turbina e\u00f3lica presentada en Santander<\/h2>\n<p>Durante unos d\u00edas, estuvo expuesta una novedosa turbina e\u00f3lica en la ciudad de Santander, emplazado junto al Palacio de la Magdalena y ha llamado la atenci\u00f3n de los transe\u00fantes por su gran tama\u00f1o y su particular forma apta para lograr la mayor eficiencia.<\/p>\n<p>Se trata de<strong> Soleolico, un aerogenerador<\/strong> que tiene la particularidad de utilizar en un solo desarrollo la energ\u00eda solar y la e\u00f3lica generando un 25% m\u00e1s de electricidad que otros sistemas convencionales y con la particularidad de absolver y convertir el carbono de la atm\u00f3sfera.<\/p>\n<p>El primer prototipo de la compa\u00f1\u00eda Soleolico presentado en un espacio urbano tiene una forma de \u00e1rbol inteligente dotado de tres alas, o velas como las denomina el fabricante, con capacidad para cuatro m\u00f3dulos solares en cada una de ellas. Aunque el modelo permite su personalizaci\u00f3n de acuerdo a las necesidades.<\/p>\n<p>Esta <strong>tecnolog\u00eda h\u00edbrida de turbina e\u00f3lica que revoluciona el sector energ\u00e9tico<\/strong> de las renovables puede generar electricidad gratis para cuatro viviendas, lo que se traducir\u00eda en una reducci\u00f3n sostenible en las facturas de luz y un camino fiable hacia el autoconsumo total en barrios y ciudades enteras.<\/p>\n<h2>Caracter\u00edsticas del nuevo aerogenerador solar<\/h2>\n<p>Pablo Fern\u00e1ndez de la Torre, el director general de Soleolico, la empresa que da el nombre al dispositivo que ha patentado su tecnolog\u00eda, reconoci\u00f3 que este proyecto es el resultado de diez a\u00f1os de b\u00fasqueda en el que se han invertido m\u00e1s de 5 millones de euros.<\/p>\n<p>Luego de crear m\u00e1s de treinta prototipos diferentes, han encontrado la forma de <strong>combinar dos sistemas de captaci\u00f3n, acumulaci\u00f3n y generaci\u00f3n de electricidad<\/strong> con el adicional valor agregado que su tecnolog\u00eda puede purificar el aire.<\/p>\n<p>La turbina e\u00f3lica tiene la capacidad de adaptarse al espacio y a las condiciones clim\u00e1ticas a medida, ya que sus brazos de 2 metros pueden expandirse hasta los 5 metros de longitud dependiendo de la velocidad del viento.<\/p>\n<p>Estas velas son<strong> capaces de girar a 6 revoluciones por minuto sin ocasionar ruidos molestos<\/strong> y generar electricidad con vientos de 12 km\/h, soportando r\u00e1fagas de hasta 80 km\/h. Su condici\u00f3n e\u00f3lica convierte a este aerogenerador en el m\u00e1s eficiente, aumentando un 25% su capacidad de conversi\u00f3n.<\/p>\n<p>En este sentido, una sola turbina e\u00f3lica tiene una potencia de 10 KW y puede ofrecer 7,5 kW promedio de energ\u00eda, con vientos inferiores a 50 km\/h, y 4,6 kW de energ\u00eda fotovoltaica, con un almacenamiento en bater\u00eda de un m\u00e1ximo de 20 kWh.<\/p>\n<h2>Ventajas sostenibles de la turbina e\u00f3lica<\/h2>\n<p>Adem\u00e1s de sus propiedades eficientes de generaci\u00f3n de energ\u00eda, este particular \u00e1rbol inteligente tiene la <strong>capacidad de absorber y transformar el di\u00f3xido de carbono<\/strong> y otros gases nocivos del ambiente a trav\u00e9s de un recubrimiento propio impreso en 3D con agentes naturales.<\/p>\n<p>Esta tecnolog\u00eda que purifica el aire de un espacio urbano transforma los gases de efecto invernadero en carbonatos o sales neutras y ox\u00edgeno. Esta caracter\u00edstica convierte a la turbina e\u00f3lica en un aliado sostenible para parques industriales, puertos, gasolineras, entre otros.<\/p>\n<p>En este contexto, la compa\u00f1\u00eda ha resaltado en la presentaci\u00f3n del primer prototipo que una instalaci\u00f3n de<strong> 1.000 unidades de Soleolico puede absorber la misma cantidad de di\u00f3xido de carbono que 287 \u00e1rboles en un a\u00f1o<\/strong>.<\/p>\n<p>En efecto, su capacidad de ofrecer energ\u00eda verde durante las 24 horas, la captaci\u00f3n y transformaci\u00f3n de emisiones, su m\u00ednimo impacto visual y sonoro y su f\u00e1cil instalaci\u00f3n hacen de esta turbina e\u00f3lica una alternativa muy buena para la <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/paneles-solares-electricidad-gratis\/6833\/\">generaci\u00f3n de energ\u00edas sostenibles en ciudades<\/a>. La compa\u00f1\u00eda espera captar el 1% del sector e instalar varias de sus torres en otras urbes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En busca de soluciones sostenibles adaptables en \u00e1reas urbanas, se han desarrollado proyectos de generaci\u00f3n de energ\u00eda renovable como las &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Esta turbina e\u00f3lica genera electricidad en casa y purifica el aire: es como si tuvieras 300 \u00e1rboles\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/turbina-eolica-purifica-aire\/7716\/#more-7716\" aria-label=\"Leer m\u00e1s sobre Esta turbina e\u00f3lica genera electricidad en casa y purifica el aire: es como si tuvieras 300 \u00e1rboles\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":7717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7716"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7717"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}