{"id":7857,"date":"2024-06-24T16:30:01","date_gmt":"2024-06-24T14:30:01","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7857"},"modified":"2024-06-24T16:30:01","modified_gmt":"2024-06-24T14:30:01","slug":"energia-eolica-espana-prohibicion","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/energia-eolica-espana-prohibicion\/7857\/","title":{"rendered":"Espa\u00f1a quiere prohibir la energ\u00eda e\u00f3lica por este motivo: el da\u00f1o oculto que hemos descubierto"},"content":{"rendered":"<p>La transici\u00f3n hacia las fuentes de energ\u00eda renovables es una necesidad que no puede postergarse. Sin embargo, es importante tener un plan detallado que prevenga incidencias como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/catastrofe-con-la-energia\/7349\/\">el grave error que cometi\u00f3 Alemania con la energ\u00eda<\/a>. Ahora, <strong>Espa\u00f1a podr\u00eda prohibir la energ\u00eda e\u00f3lica<\/strong> debido a la muerte de millones de aves que ha revelado un informe presentado por cuatro entidades conservacionistas.<\/p>\n<h2>Espa\u00f1a quiere prohibir la energ\u00eda e\u00f3lica<\/h2>\n<p>La energ\u00eda e\u00f3lica es una fuente renovable de electricidad que ofrece una mayor eficiencia y estabilidad que otras fuentes como la energ\u00eda solar. Se trata de una tecnolog\u00eda limpia que actualmente <strong>aporta alrededor del 20% de la electricidad de toda Europa<\/strong>. La UE se ha establecido como l\u00edder en este tipo de energ\u00eda y cada vez son m\u00e1s y m\u00e1s grandes los parques e\u00f3licos que se instalan en el territorio.<\/p>\n<p>Sin embargo, para alimentar las redes el\u00e9ctricas con este tipo de energ\u00eda, se requieren grandes extensiones de tierra donde se instalan monumentales molinos. Las grandes aspas que aportan la fuerza necesaria para mover las turbinas generadoras hacen que la zona donde se instalen deba estar despejada, ya que impide el crecimiento de vegetaci\u00f3n y representa un riesgo para las aves.<\/p>\n<p>La <strong>mortandad de aves en los parques e\u00f3licos<\/strong> es una problem\u00e1tica de la que se viene advirtiendo hace tiempo y ahora ha escalado a un punto cr\u00edtico. Cuatro organizaciones de preservaci\u00f3n de la fauna y la vegetaci\u00f3n han presentado informes preocupantes. En los mismos consta la muerte de entre uno y dos millones de aves anualmente y, en muchos casos, en zonas protegidas por acuerdos internacionales.<\/p>\n<h2>El problema de las \u00e1reas protegidas<\/h2>\n<p>Seg\u00fan consta en las regulaciones que debe cumplir cualquier parque e\u00f3lico, las comunidades aut\u00f3nomas donde se instalen los mismos deben proveer datos sobre el impacto de los molinos. Seg\u00fan las entidades que denuncian la irregularidad, los reportes presentados por los municipios constan la muerte de unas 9000 aves anualmente, pero los expertos dicen que esta informaci\u00f3n est\u00e1 incompleta.<\/p>\n<p>Se tiene constancia de que las autoridades no cuentan con metodolog\u00edas eficaces para el recorrido de los parques e\u00f3licos y la recolecci\u00f3n de cuerpos de aves para realizar un buen relevamiento. Adem\u00e1s, muchos municipios ni siquiera han llegado a aportar datos, por lo que las organizaciones han encargado sus propios estudios y<strong> se han encontrado con una realidad muy preocupante<\/strong>.<\/p>\n<p>Seg\u00fan estimaciones respaldadas por diversas autoridades de la comunidad cient\u00edfica, el n\u00famero de muertes anuales de aves podr\u00eda abarcar entre <strong>1.3 y 2 millones de ejemplares muertos<\/strong> a causa de los parques e\u00f3licos. Lo m\u00e1s apremiante es que muchos de los generadores est\u00e1n instalados en zonas protegidas por la Red Natura 2000 y otras \u00e1reas registradas c\u00f3mo h\u00e1bitat de especies amenazadas.<\/p>\n<h2>\u00bfQu\u00e9 pasar\u00e1 con la energ\u00eda e\u00f3lica?<\/h2>\n<p>Las fundaciones que est\u00e1n denunciando esta problem\u00e1tica exigen un relevamiento m\u00e1s adecuado de las \u00e1reas donde se instalan los parques e\u00f3licos, tanto si pertenecen a la Red Natura 2000 como a otras zonas protegidas como los humedales. Los expertos esperan que se empiece por <strong>prohibir la energ\u00eda e\u00f3lica en estos sitios<\/strong>, aunque, seg\u00fan consta en las legislaciones, esto ya estaba estipulado.<\/p>\n<p>Tambi\u00e9n se ha constado en el reclamo la existencia de tecnolog\u00eda preventiva como radares para evitar los accidentes con las aves y no hacer efecto barrera donde pudiera haber cursos migratorios.<\/p>\n<h2>El complejo camino a la sustentabilidad<\/h2>\n<p>Prohibir la energ\u00eda e\u00f3lica es una medida que no podemos permitirnos, si queremos reducir las emisiones de CO2 cero para el 2050. Sin embargo, debemos encontrar una manera de que no nos cueste la p\u00e9rdida de otros recursos naturales. Tecnolog\u00edas como <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/baterias-para-producir-energia\/7708\/\">las bater\u00edas para energ\u00eda solar<\/a> podr\u00edan permitirnos sacar el m\u00e1ximo provecho posible de esta fuente renovable sin causar otros problemas ambientales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La transici\u00f3n hacia las fuentes de energ\u00eda renovables es una necesidad que no puede postergarse. Sin embargo, es importante tener &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a quiere prohibir la energ\u00eda e\u00f3lica por este motivo: el da\u00f1o oculto que hemos descubierto\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/energia-eolica-espana-prohibicion\/7857\/#more-7857\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a quiere prohibir la energ\u00eda e\u00f3lica por este motivo: el da\u00f1o oculto que hemos descubierto\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":7911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7857"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7911"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}