{"id":7940,"date":"2024-06-26T16:30:30","date_gmt":"2024-06-26T14:30:30","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7940"},"modified":"2024-06-26T16:30:30","modified_gmt":"2024-06-26T14:30:30","slug":"panel-solar-de-diamante","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/panel-solar-de-diamante\/7940\/","title":{"rendered":"Logran encender el panel solar de diamante por primera vez: nadie se esperaba lo que ha hecho con el Sol"},"content":{"rendered":"<p>La Uni\u00f3n Europea ha conseguido erigirse como l\u00edder en energ\u00eda solar tras haber realizado numerosas inversiones y un arduo y largo trabajo, aunque todav\u00eda debemos resolver algunos obst\u00e1culos en cuanto a la eficiencia. <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/baterias-para-producir-energia\/7708\/\">Las bater\u00edas para energ\u00eda solar<\/a> podr\u00edan ser un excelente complemento si se combina con <strong>el nuevo panel solar de diamante<\/strong> que parece haber sido un \u00e9xito en las recientes pruebas.<\/p>\n<h2>El primer panel solar de diamante: adi\u00f3s al silicio y a la perovskita (que acababa de llegar)<\/h2>\n<p>En la actualidad, la energ\u00eda solar es una fuente alternativa que est\u00e1 cobrando cada vez mayor relevancia en el mix el\u00e9ctrico de la UE. Sin embargo, <strong>la eficiencia sigue siendo un gran obst\u00e1culo para que se pueda obtener un suministro eficiente<\/strong> y estable de energ\u00eda fotovoltaica. Es por eso que se siguen investigando nuevos materiales alternativos al silicio como las perovskitas y, ahora, el diamante.<\/p>\n<p>El silicio es el material transl\u00facido que habitualmente recubre las celdas fotovoltaicas y permite la captaci\u00f3n de radiaci\u00f3n solar para convertirla en electricidad libre de emisiones. No obstante, es un material proclive al desgaste y la degradaci\u00f3n por causa del calor. De ah\u00ed la necesidad de encontrar nuevos materiales alternativos, m\u00e1s eficientes y resistentes.<\/p>\n<p>Ahora, expertos de diferentes \u00e1reas han realizado pruebas para su nuevo panel solar de diamante con resultados muy prometedores. El diamante tiene una gran capacidad de captaci\u00f3n de luz, lo que lo hace muy bueno para la energ\u00eda solar, y, a\u00f1adiendo ciertos componentes, se puede convertir en <strong>uno de los semiconductores m\u00e1s eficientes<\/strong> conocidos hasta ahora, incluso m\u00e1s que las perovskitas.<\/p>\n<h2>Las ventajas de los diamantes: un material caro, pero que podr\u00eda revolucionar la fotovoltaica<\/h2>\n<p>El diamante es <strong>el material con mayor conductividad t\u00e9rmica que conocemos<\/strong>. Esto representar\u00eda una gran soluci\u00f3n al mayor problema del silicio, que es el gran desgaste que genera el calor del sol en su estructura. Es capaz tambi\u00e9n de captar un espectro de luz mucho m\u00e1s amplio que su predecesor, lo que le permitir\u00eda obtener mucha m\u00e1s energ\u00eda con la misma superficie que las celdas actuales.<\/p>\n<p>Como es bien sabido, este mineral es uno de los m\u00e1s resistentes de nuestro planeta, lo que har\u00eda que el nuevo panel solar de diamante sea mucho m\u00e1s duradero que los tradicionales de silicio o incluso los que emplean perovskitas. De esta manera, a\u00f1adiendo una delgada capa de diamante sint\u00e9tico a los paneles solares, se podr\u00eda conseguir mucha m\u00e1s energ\u00eda con un generador mucho m\u00e1s duradero.<\/p>\n<p>Es destacable tambi\u00e9n el hecho de que ya contamos con una amplia experiencia en la producci\u00f3n de diamante sint\u00e9tico para diferentes aplicaciones en un amplio espectro de \u00e1reas. Usando los m\u00e9todos conocidos para producir este mineral, se podr\u00eda generar una delgada capa de diamante que ir\u00eda sobre las celdas solares por medio de <strong>Deposici\u00f3n Qu\u00edmica de Vapor (DCV)<\/strong>.<\/p>\n<h2>Los desaf\u00edos del panel solar de diamante: no sol su precio, sino la competencia de Rusia<\/h2>\n<p>El primer y m\u00e1s importante obst\u00e1culo para esta tecnolog\u00eda es su elevado precio de producci\u00f3n. El silicio es la alternativa, hasta ahora, m\u00e1s accesible para el recubrimiento de celdas solares. Las perovskitas, por su parte, pueden producirse tambi\u00e9n a partir de procesos y materiales baratos y ofrece una eficiencia mucho mayor que el silicio.<\/p>\n<p>La fabricaci\u00f3n de diamante sint\u00e9tico de alta calidad, en cambio, sigue teniendo un elevado coste de fabricaci\u00f3n. No obstante, de implementarse, este material <strong>podr\u00eda permitir a los paneles solares superar todas las limitaciones te\u00f3ricas existentes<\/strong> hasta el momento, por lo que vale la pena seguir investigando.<\/p>\n<h3>El futuro de la energ\u00eda solar<\/h3>\n<p>La implementaci\u00f3n de esta revolucionaria tecnolog\u00eda podr\u00eda dar mucho mayor impulso a <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-arboles-fotovoltaicos\/7653\/\">los \u00e1rboles fotovoltaicos que ya se est\u00e1n instalando en Espa\u00f1a<\/a>. La posibilidad de elevar las capacidades de los generadores fotovoltaicos m\u00e1s all\u00e1 de todos los l\u00edmites conocidos promete un gran futuro para la fuerte inversi\u00f3n que viene realizando nuestro pa\u00eds desde hace varios a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Europea ha conseguido erigirse como l\u00edder en energ\u00eda solar tras haber realizado numerosas inversiones y un arduo y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Logran encender el panel solar de diamante por primera vez: nadie se esperaba lo que ha hecho con el Sol\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/panel-solar-de-diamante\/7940\/#more-7940\" aria-label=\"Leer m\u00e1s sobre Logran encender el panel solar de diamante por primera vez: nadie se esperaba lo que ha hecho con el Sol\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":7988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7940"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7988"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}