{"id":7954,"date":"2024-06-27T17:00:00","date_gmt":"2024-06-27T15:00:00","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=7954"},"modified":"2024-06-27T17:00:00","modified_gmt":"2024-06-27T15:00:00","slug":"islas-tierras-raras-canarias","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/islas-tierras-raras-canarias\/7954\/","title":{"rendered":"Portugal y Marruecos nos quieren quitar estas islas: la ONU quiere este tesoro que hay en el fondo del mar"},"content":{"rendered":"<p>Varias empresas se han interesado en tiempos recientes por los <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-tierras-raras-tesoro-mar\/7683\/\">dep\u00f3sitos de tierras raras bajo las Islas Canarias que podr\u00eda valer billones de euros<\/a>. La extracci\u00f3n es compleja y costosa, raz\u00f3n por la cual todav\u00eda no se ha explotado este tesoro que hay en el fondo de nuestro mar. Ahora, una pol\u00e9mica est\u00e1 creciendo tras las <strong>dudosas operaciones que Portugal y Marruecos han realizado recientemente<\/strong>.<\/p>\n<h2>La disputa por este tesoro bajo las Islas Canarias<\/h2>\n<p>Recientes exploraciones submarinas en el territorio de las Islas Canarias han revelado <strong>enormes yacimientos de telurio y tierras raras<\/strong> que son indispensables para tecnolog\u00edas como telecomunicaciones, dispositivos electr\u00f3nicos y bater\u00edas de coches el\u00e9ctricos. Este tesoro se encuentra a cientos de metros en el fondo del mar, por lo que su explotaci\u00f3n requiere de muchos estudios y relevamientos.<\/p>\n<p>El foco de mayor importancia es la imponente monta\u00f1a submarina Tr\u00f3pico, cuya superficie concentra una de las mayores acumulaciones de tierras raras. De ser posible la explotaci\u00f3n del yacimiento, se podr\u00edan producir millones de coches el\u00e9ctricos sin la necesidad de importar materias primas desde China, lo cual representar\u00eda grandes beneficios para la UE.<\/p>\n<p>Pero, mientras Espa\u00f1a estudia el impacto de la actividad en los ecosistemas marinos, una serie de operaciones de buques portugueses muy cerca de la plataforma submarina de nuestro pa\u00eds han hecho sonar las alarmas. Las autoridades advierten que <strong>Marruecos podr\u00eda estar contratando buques de nuestro pa\u00eds vecino<\/strong> para obtener beneficios de recursos estrat\u00e9gicos de nuestro territorio.<\/p>\n<h2>La disputa por la ZEE<\/h2>\n<p>La ONU est\u00e1 intentando <strong>diversificar las fuentes de extracci\u00f3n de tierras raras<\/strong>, ya que, en su mayor\u00eda, provienen de pa\u00edses en desarrollo donde las condiciones de trabajo son muy malas y las pr\u00e1cticas para ello amenazan al medio ambiente. Sin embargo, la situaci\u00f3n es compleja y eso se refleja en el reclamo que Espa\u00f1a viene realizando para extender su Zona de Explotaci\u00f3n Exclusiva sin \u00e9xito.<\/p>\n<p>Esta problem\u00e1tica ha cobrado nuevo protagonismo en el tablero internacional tras algunas inconsistencias en la actividad del buque de exploraci\u00f3n <strong>NI Mario Ruivo<\/strong>, fondeado al sur de las Islas Canarias en nuestra ZEE.<\/p>\n<p>La embarcaci\u00f3n tiene la capacidad de relevar estructuras y yacimientos marinos hasta 11000 metros de profundidad. La pol\u00e9mica viene por el hecho de que el nav\u00edo se encuentra muy cerca de Tr\u00f3pico, y muchas veces se ha encontrado que opera con sus sistemas de rastreo y comunicaci\u00f3n apagados. El yacimiento de tierras raras se extiende en una zona sin regular muy cerca de nuestra ZEE.<\/p>\n<h2>Una compleja red de intereses<\/h2>\n<p>Portugal es uno de los pocos pa\u00edses extranjeros a los que Espa\u00f1a permite realizar operaciones en su ZEE. Sin embargo, se tiene registro de que la embarcaci\u00f3n <strong>realiz\u00f3 un cambio de tripulaci\u00f3n antes de establecerse en su ubicaci\u00f3n actual<\/strong>.<\/p>\n<p>Este tesoro bajo el mar ya est\u00e1 en disputa entre Marruecos y Espa\u00f1a, desde que se estableci\u00f3 la zona de control del Sahara. La ONU todav\u00eda est\u00e1 determinando los derechos de cada pa\u00eds de acuerdo a las legislaciones actuales, pero parece que Marruecos no desea perder tiempo en burocracia.<\/p>\n<p>Las autoridades mar\u00edtimas espa\u00f1olas advierten la posibilidad de que Marruecos est\u00e9 <strong>subcontratando el uso del buque portugu\u00e9s para realizar relevamientos<\/strong> en zonas donde las regulaciones de explotaci\u00f3n de la ONU no tienen alcance. Estas zonas est\u00e1n muy cerca de nuestra plataforma submarina y ocupa un \u00e1rea que Espa\u00f1a viene reclamando desde hace casi una d\u00e9cada.<\/p>\n<h2>Una disputa que podr\u00eda escalar<\/h2>\n<p>Europa tiene una gran necesidad de fuentes de tierras raras para dejar de depender del monopolio chino cuanto antes. Si Portugal toma parte en <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-tesoro-4000-profundidad\/7499\/\">la disputa entre Espa\u00f1a y Marruecos por la monta\u00f1a submarina Tr\u00f3pico<\/a>, podr\u00edamos enfrentar una seria serie sacudida en las relaciones internacionales con nuestros vecinos, por lo que una actualizaci\u00f3n de la ZEE se hace m\u00e1s urgente que nunca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varias empresas se han interesado en tiempos recientes por los dep\u00f3sitos de tierras raras bajo las Islas Canarias que podr\u00eda &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Portugal y Marruecos nos quieren quitar estas islas: la ONU quiere este tesoro que hay en el fondo del mar\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/islas-tierras-raras-canarias\/7954\/#more-7954\" aria-label=\"Leer m\u00e1s sobre Portugal y Marruecos nos quieren quitar estas islas: la ONU quiere este tesoro que hay en el fondo del mar\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":7977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=7954"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/7954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/7977"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=7954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=7954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=7954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}