{"id":8878,"date":"2024-07-23T15:00:16","date_gmt":"2024-07-23T13:00:16","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=8878"},"modified":"2024-07-23T15:00:16","modified_gmt":"2024-07-23T13:00:16","slug":"ladrillo-cana-de-azucar-edificios","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/ladrillo-cana-de-azucar-edificios\/8878\/","title":{"rendered":"Este \u00abladrillo dulce\u00bb levantar\u00e1 los edificios del futuro: ventilaci\u00f3n gratis y energ\u00eda desde las paredes"},"content":{"rendered":"<p>Los incre\u00edbles avances tecnol\u00f3gicos que se est\u00e1n desarrollando para sustituir al hormig\u00f3n est\u00e1n dando unos resultados sorprendentes, como es el caso de <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/hormigon-atmosfera-gas-casas\/7491\/\">este ladrillo sostenible<\/a>. Sin embargo, ahora ha aparecido un<strong> nuevo ladrillo dulce que promete amplias garant\u00edas de seguridad para grandes edificios ubicados en zonas s\u00edsmicas<\/strong> y reduce la utilizaci\u00f3n del acero en la construcci\u00f3n.<\/p>\n<h2>Un ladrillo dulce apto para las construcciones s\u00edsmicas<\/h2>\n<p>Con el fin de disminuir la cantidad de emisiones de carbono en la construcci\u00f3n mundial, las tecnolog\u00edas a base de materiales residuales org\u00e1nicas vienen ganando un espacio vital. Es as\u00ed como ha surgido este novedoso ladrillo con caracter\u00edsticas muy resistentes y estables.<\/p>\n<p>Un equipo compuesto por arquitectos de la Universidad del Este de Londres (UEL) interesados en<strong> crear un dispositivo que sustituyera al hormig\u00f3n a partir de desechos org\u00e1nicos<\/strong>, descubrieron las potencialidades del material vegetal de la ca\u00f1a de az\u00facar para desarrollar un nuevo ladrillo.<\/p>\n<p>Debido al r\u00e1pido crecimiento y renovaci\u00f3n de la planta, el alto volumen de residuos generado en la industria azucarera y su comprobada calidad de eficiencia, se obtuvo un resultado m\u00e1s dulce de lo esperado luego de tres a\u00f1os de desarrollo.<\/p>\n<p>El resultado obtenido confirm\u00f3 que el ladrillo vegetal y dulce de consistencia ligera y asequible ten\u00eda virtudes mec\u00e1nicas resistente a los terremotos con cero emisiones de carbono. <strong>Sugarcrete, as\u00ed como se denomina, es una mezcla patentada<\/strong> ganadora de premios como el prestigioso Climate Positive de Green Cross UK.<\/p>\n<h2>Sugarcrete, el ladrillo ecol\u00f3gico m\u00e1s resistente<\/h2>\n<p>La f\u00f3rmula compuesta por el bagazo de la ca\u00f1a de az\u00facar y aglutinantes minerales que se comprimi\u00f3 hasta obtener la forma deseada estuvo lista luego de tan solo una semana de curaci\u00f3n, cuando el hormig\u00f3n necesita casi un mes de reposo.<\/p>\n<p>El experimento cont\u00f3 con el apoyo de la azucarera Tate &amp; Lyle Sugars de quien obtuvieron suficiente bagazo para desarrollar la f\u00f3rmula y el estudio de arquitectura Grimshaw, quien ya ven\u00eda trabajando con <strong>distintos dispositivos ecol\u00f3gicos para sustituir al hormig\u00f3n<\/strong><\/p>\n<p>El ladrillo pas\u00f3 por diversas instancias evaluativas para comprobar su resistencia al fuego y a la compresi\u00f3n, as\u00ed como su conductividad t\u00e9rmica y durabilidad en las instalaciones del Instituto de Investigaci\u00f3n sobre Sostenibilidad (SRI).<\/p>\n<p>Los resultados obtenidos aseguran<strong> unas emisiones de carbono veinte veces menores<\/strong> a las del proceso de fabricaci\u00f3n de hormig\u00f3n, una ligereza cinco veces mayor y un coste m\u00e1s barato. Una vez comprobadas todas estas caracter\u00edsticas, los arquitectos fueron hacia un desaf\u00edo mayor.<\/p>\n<h2>El Sugarcrete Lab modular se arma y desarma como un piso de legos<\/h2>\n<p>La potencialidad de los ladrillos de ca\u00f1a de az\u00facar no solo es transferible para la construcci\u00f3n de muros y paredes. Los arquitectos fabricaron bloques modulares de piezas desmontables para generar lozas m\u00e1s resistentes, adaptables y reciclables con capacidades mec\u00e1nicas \u00fanicas.<\/p>\n<p>El Sugarcrete Lab, adem\u00e1s de ser resistentes al fuego es una losa compuesta por m\u00f3dulos con m\u00e9todo de sujeci\u00f3n mediante tirantes postensados que ofrece mayor resistencia de carga y <strong>puede sustituir al acero en un 90% de la construcci\u00f3n.<\/strong><\/p>\n<p>Seg\u00fan advierte Elena Shilova, una de las arquitectas integrantes del estudio, la reducci\u00f3n de acero combinado con las fibras de ca\u00f1a de az\u00facar reduce la aparici\u00f3n de grietas propias en las estructuras de hormig\u00f3n. La f\u00f3rmula innovadora del ladrillo dulce absorbe eficientemente los efectos del choque s\u00edsmico.<\/p>\n<p>El resultante tiene suficiente potencial para ser utilizado para paneles aislantes, bloques ligeros, bloques de carga y losas estructurales para suelos y tejados, y puede ser ampliamente utilizado en las regiones con<strong> una econom\u00eda basada en la producci\u00f3n de ca\u00f1a de az\u00facar y propensas a los terremotos<\/strong>.<\/p>\n<p>La iniciativa inglesa que reduce las emisiones y los costes considerablemente con este ladrillo org\u00e1nico quiere llegar a los pa\u00edses que importan altas proporciones de hormig\u00f3n y que cuentan con plantaciones de ca\u00f1a de az\u00facar para fomentar la elaboraci\u00f3n propia de una soluci\u00f3n sostenible. Es una muy buena alternativa, as\u00ed como lo es <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/casas-del-futuro-lego-adios-ladrillo\/7319\/\">este ladrillo fabricado a partir del reciclaje de desechos<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los incre\u00edbles avances tecnol\u00f3gicos que se est\u00e1n desarrollando para sustituir al hormig\u00f3n est\u00e1n dando unos resultados sorprendentes, como es el &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Este \u00abladrillo dulce\u00bb levantar\u00e1 los edificios del futuro: ventilaci\u00f3n gratis y energ\u00eda desde las paredes\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/ladrillo-cana-de-azucar-edificios\/8878\/#more-8878\" aria-label=\"Leer m\u00e1s sobre Este \u00abladrillo dulce\u00bb levantar\u00e1 los edificios del futuro: ventilaci\u00f3n gratis y energ\u00eda desde las paredes\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":8879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/8878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=8878"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/8878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/8879"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=8878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=8878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=8878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}