{"id":9203,"date":"2024-08-07T16:00:14","date_gmt":"2024-08-07T14:00:14","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=9203"},"modified":"2024-08-07T16:00:14","modified_gmt":"2024-08-07T14:00:14","slug":"einstein-motor-espacio","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/einstein-motor-espacio\/9203\/","title":{"rendered":"Einstein predijo un motor que distorsiona el espacio, y lo han creado: revienta al hidr\u00f3geno y a los el\u00e9ctricos"},"content":{"rendered":"<p><strong>Einstein<\/strong> predijo un <strong>motor que distorsiona el espacio<\/strong> y ya es una realidad. Revienta el hidr\u00f3geno y los el\u00e9ctricos. El <a href=\"https:\/\/www.ecoticias.com\/movilidad-electrica\/hidrogeno-motor-liquido\">primer motor de hidr\u00f3geno l\u00edquido espa\u00f1ol<\/a> gener\u00f3 una gran expectaci\u00f3n en el mundo, un furor que se multiplica con la pieza de que la vamos a hablar a continuaci\u00f3n. Dado el contexto, cabe recordar la<strong> teor\u00eda de la relatividad<\/strong> que defend\u00eda <strong>Einstein<\/strong>. Explica la relaci\u00f3n entre masa, espacio, tiempo y energ\u00eda y la gravedad como consecuencia de la curvatura del espacio-tiempo. Esta teor\u00eda general fue publicada en 1915 y describe el comportamiento de los cuerpos en campos gravitacionales de cualquier tipo.<\/p>\n<p>La teor\u00eda defiende que el ser humano vive en un universo de cuatro dimensiones: el espacio-tiempo. Con esta teor\u00eda, <strong>Einstein<\/strong> revolucion\u00f3 la forma en la que la humanidad comprend\u00eda el universo y demostr\u00f3 que el espacio, el tiempo y la gravedad son aspectos interrelacionados. El supuesto b\u00e1sico de la teor\u00eda de<strong> Einstein<\/strong> (la teor\u00eda de la relatividad) es que la localizaci\u00f3n de los sucesos f\u00edsicos, tanto en tiempo como en espacio, son relativos al estado de movimiento del observador.<\/p>\n<p>De esta manera, la longitud de un objeto en movimiento y el instante en que pasa no es un invariante absoluta. Es decir, las longitudes y los intervalos temporales en relatividad no son absolutos, sino relativos.<\/p>\n<h2>El motor que predijo Einstein se materializa: deja el hidr\u00f3geno a un lado<\/h2>\n<p>El <strong>motor de curvatura<\/strong> ya est\u00e1 aqu\u00ed. Un grupo de f\u00edsicos ha desarrollado un innovador concepto de propulsi\u00f3n que supone el comienzo de una nueva competencia espacial en el siglo XXI, similar a la de la <strong>Guerra Fr\u00eda<\/strong>. Un motor <em>warp drive<\/em> (o motor de curvatura) se trata de una<strong> idea te\u00f3rica de propulsi\u00f3n especial<\/strong> que har\u00eda posible <strong>los viajes a velocidades superiores a la de la luz<\/strong>, alterando o \u2018curvando\u2019 el espacio-tiempo alrededor de la nave.<\/p>\n<p>Este concepto ha ganado una importante popularidad debido a<strong> Star Trek<\/strong>, una franquicia de ciencia ficci\u00f3n que presenta naves espaciales con motores de curvatura para desplazarme r\u00e1pido por el universo. Aunque este t\u00e9rmino se asocie con la ciencia ficci\u00f3n por la serie de televisi\u00f3n hom\u00f3nima, existen varios grupos de ingenieros y f\u00edsicos dedicados al desarrollo del primer motor <em>warp drive<\/em>.<\/p>\n<p><strong>Gianni Martie<\/strong>, cofundador de <strong>Applied Physics<\/strong>, una organizaci\u00f3n sin \u00e1nimo de lucro formada por astrof\u00edsicos e ingenieros, trabaja para crear herramientas que permitan la construcci\u00f3n del primer motor de deformaci\u00f3n del espacio-tiempo. En una entrevista con <em>The Debrief<\/em>, expuso que el <em>warp drive<\/em> es posible y la primera demostraci\u00f3n con un prototipo de laboratorio est\u00e1 m\u00e1s cerca que nunca.<\/p>\n<p>El motor de curvatura est\u00e1 basado en que es posible <strong>contraer el espacio delante de una nave espacial y expandir el espacio tras ella<\/strong>, forjando una \u201cburbuja de curvatura\u201d que moviliza la nave. En el interior de la burbuja, la nave no se mover\u00eda m\u00e1s r\u00e1pido que la luz localmente, pero la burbuja consentir\u00eda un desplazamiento efectivo a velocidades superiores a la de la luz.<\/p>\n<h2>Ya se habla del motor que distorsiona el espacio: Einstein ya lo predijo<\/h2>\n<p>En 1994, el f\u00edsico te\u00f3rico <strong>Miguel Alcubierre<\/strong> propuso una soluci\u00f3n matem\u00e1tica conocida como la \u2018m\u00e9trica de <strong>Alcubierre<\/strong>\u2019 que describe c\u00f3mo realizarse la formaci\u00f3n de una burbuja de curvatura. Siguiendo este modelo, podr\u00eda conseguirse un viaje m\u00e1s r\u00e1pido que la luz sin vulnerar las leyes fundamentales de la f\u00edsico, ya que el espacio mismo se mover\u00eda y no la nave en su interior.<\/p>\n<p>No obstante, el <strong>motor de curvatura<\/strong> afronta importantes desaf\u00edos que hacen complicada su fabricaci\u00f3n y alejan las posibilidades de que alg\u00fan d\u00eda llegue a ser una realidad. La m\u00e9trica de <strong>Alcubierre<\/strong> necesita un tipo de \u2018energ\u00eda ex\u00f3tica\u2019 con densidad de energ\u00eda negativa, una forma de energ\u00eda que todav\u00eda no ha demostrado su existencia en la naturaleza.<\/p>\n<p>Incluso si este tipo de energ\u00eda fuera viable, la cantidad requerida para la formaci\u00f3n de una burbuja de curvatura ser\u00eda muy grande, posiblemente del orden de la masa-energ\u00eda de planetas enteros. Por otra parte, la estabilidad de una burbuja de curvatura y c\u00f3mo controlarla son temas que todav\u00eda necesitan soluci\u00f3n.<\/p>\n<p>Pese a los desaf\u00edos, algunos cient\u00edficos siguen explorando conceptos te\u00f3ricos y crean experimentos que podr\u00edan acercarnos al <strong>motor que predijo Einstein<\/strong>. Si finalmente se concreta, el impacto ser\u00eda tan grande como el ocasionado por el \u201c<a href=\"https:\/\/www.ecoticias.com\/movilidad-electrica\/motor-electricidad-hidogeno\">combustible milagro<\/a>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einstein predijo un motor que distorsiona el espacio y ya es una realidad. Revienta el hidr\u00f3geno y los el\u00e9ctricos. El &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Einstein predijo un motor que distorsiona el espacio, y lo han creado: revienta al hidr\u00f3geno y a los el\u00e9ctricos\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/einstein-motor-espacio\/9203\/#more-9203\" aria-label=\"Leer m\u00e1s sobre Einstein predijo un motor que distorsiona el espacio, y lo han creado: revienta al hidr\u00f3geno y a los el\u00e9ctricos\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":9403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movilidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=9203"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/9403"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=9203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=9203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=9203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}