{"id":9433,"date":"2024-08-09T15:00:44","date_gmt":"2024-08-09T13:00:44","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=9433"},"modified":"2024-08-09T15:00:44","modified_gmt":"2024-08-09T13:00:44","slug":"construccion-barro-sostenible","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/construccion-barro-sostenible\/9433\/","title":{"rendered":"La construcci\u00f3n recupera un material del Paleol\u00edtico: mitiga el calor en verano y no lo sab\u00edamos"},"content":{"rendered":"<p>El sector de la construcci\u00f3n est\u00e1 en el foco de atenci\u00f3n por quienes abogan por un mundo m\u00e1s sostenible y respetuoso con la naturaleza. De acuerdo a su alto nivel de contaminaci\u00f3n, cada innovaci\u00f3n constructiva se analiza desde una perspectiva verde que eval\u00faa su potencial de eficiencia en tanto sea sostenible. Sin embargo, <strong>este antiguo material no tiene discusi\u00f3n y mantiene sus propiedades milenarias.<\/strong><\/p>\n<h2>El ladrillo milenario que trasciende todas las \u00e9pocas y modas<\/h2>\n<p>A lo largo de la historia se han inventado una serie de materiales, algunos m\u00e1s sofisticados que otros para la construcci\u00f3n que aportan su tecnolog\u00eda, funcionalidad y dise\u00f1o a las edificaciones. No obstante, hay uno solo que no pierde vigencia por sus propiedades, m\u00e1s all\u00e1 de los sustitutos innovadores como<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/ladrillo-cana-de-azucar-edificios\/8878\/\"> este ladrillo comestible.<\/a><\/p>\n<p><strong>El material del Paleol\u00edtico que hoy sigue siendo indispensable en la construcci\u00f3n es el barro,<\/strong> conocido recurso natural que constituy\u00f3 las primeras edificaciones de la civilizaci\u00f3n para las levantar los asentamientos que dejar\u00edan atr\u00e1s la vida n\u00f3made.<\/p>\n<p>Los primeros constructores que utilizaron el barro para sus casas no sab\u00edan el potencial de propiedades que ofrece para la construcci\u00f3n, pero se sabe que se comenz\u00f3 a utilizar desde hace m\u00e1s de 11.000 a\u00f1os en la Mesopotamia, desde la civilizaci\u00f3n sumeria.<\/p>\n<h2>El material de construcci\u00f3n m\u00e1s antiguo de la historia que hoy continuamos utilizando<\/h2>\n<p>Con el paso del tiempo,<strong> el ladrillo de barro ha sido el pilar de construcci\u00f3n de grandes imperios<\/strong> y ha subsistido a todas las \u00e9pocas, ingresando desde oriente a Grecia y de all\u00ed se expandi\u00f3 por todo el mundo occidental.<\/p>\n<p>Utilizado para el adobe, una mezcla de arena y arcilla con paja secado al sol fue el principal material constructivo de todos los tiempos, ingresando a Espa\u00f1a desde Marruecos donde posteriormente se coloc\u00f3 en moldes para su fabricaci\u00f3n sistematizada.<\/p>\n<p>Con<strong> la producci\u00f3n en serie de los ladrillos de barro se complejiz\u00f3 la tecnolog\u00eda de fabricaci\u00f3n<\/strong>, comenzando a utilizar otros elementos aditivos con el objeto de lograr mayor dureza y una consistencia m\u00e1s ligera, a pesar de ser contaminantes para el medio ambiente.<\/p>\n<p>Sin embargo, el material principal de estos ladrillos sigue siendo el barro, y aqu\u00ed analizaremos sus caracter\u00edsticas y propiedades eficientes y sostenibles que resaltan la importancia de su incorporaci\u00f3n en la construcci\u00f3n incluso en la actual.<\/p>\n<h2>Las virtudes del barro en la construcci\u00f3n<\/h2>\n<p><strong>De origen natural, presencia abundante y con car\u00e1cter reciclable<\/strong>, el ladrillo de barro es un material sostenible porque cumple con las propiedades b\u00e1sicas que debe tener un material de construcci\u00f3n sin perjudicar el medio ambiente.<\/p>\n<p>Adicionalmente ofrece otras propiedades para la edificaci\u00f3n que resaltan su importancia para el modelo constructivo actual en la b\u00fasqueda de la eficiencia energ\u00e9tica, ya que tiene un alto potencial de aislaci\u00f3n t\u00e9rmica, conservando los ambientes confortables.<\/p>\n<p><strong>Su poder aislante abarca no solo su capacidad de regular la temperatura interior<\/strong>, sino que tambi\u00e9n posee caracter\u00edsticas ac\u00fasticas que minimizan los ruidos provenientes del exterior. Adem\u00e1s, tiene la capacidad de absorber el agua por lo que es un recurso \u00f3ptimo para mantener un ambiente seco libre de humedad y moho.<\/p>\n<p>A trav\u00e9s de un proceso de secado al sol o por cocci\u00f3n el ladrillo de barro para la construcci\u00f3n presenta excelentes propiedades mec\u00e1nicas y resistentes, as\u00ed como dureza y estabilidad y durabilidad apto para mantener altas estructuras pesadas por largo tiempo.<\/p>\n<h2>M\u00e1s ventajas del barro en la construcci\u00f3n que explican su uso en la actualidad<\/h2>\n<p>Su permeabilidad a la humedad contribuye a que sea un material resistente al fuego y repelente del calor, ideal para regiones con temperaturas c\u00e1lidas. Tiene <strong>muy baja necesidad de mantenimiento, es econ\u00f3mico y permite el reciclaje de sus desechos<\/strong> para volver a la tierra o para convertirse en otro ladrillo.<\/p>\n<p>Por todos estos motivos, el barro es el material de construcci\u00f3n m\u00e1s sostenible y noble que sigue vigente desde tiempos remotos por todas sus virtudes mec\u00e1nicas y de aislaci\u00f3n. Hoy se observan <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/casas-del-futuro-lego-adios-ladrillo\/7319\/\">nuevos desarrollos de ladrillos con material reciclado<\/a> o de origen natural como este pero sin dudas que el barro ser\u00e1 el principal constructor de grandes proyectos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector de la construcci\u00f3n est\u00e1 en el foco de atenci\u00f3n por quienes abogan por un mundo m\u00e1s sostenible y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La construcci\u00f3n recupera un material del Paleol\u00edtico: mitiga el calor en verano y no lo sab\u00edamos\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/construccion-barro-sostenible\/9433\/#more-9433\" aria-label=\"Leer m\u00e1s sobre La construcci\u00f3n recupera un material del Paleol\u00edtico: mitiga el calor en verano y no lo sab\u00edamos\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":9483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=9433"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=9433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=9433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=9433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}