{"id":9525,"date":"2024-08-12T16:30:55","date_gmt":"2024-08-12T14:30:55","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=9525"},"modified":"2024-08-12T16:30:55","modified_gmt":"2024-08-12T14:30:55","slug":"frontera-mas-pequena-del-mundo","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/frontera-mas-pequena-del-mundo\/9525\/","title":{"rendered":"Espa\u00f1a tiene la frontera m\u00e1s peque\u00f1a del mundo, pero nos la quieren quitar: riesgo de colapso en 2024 por este pa\u00eds"},"content":{"rendered":"<p>Espa\u00f1a es una tierra que abunda en historias y contrastes, especialmente all\u00ed donde se produjeron los choques culturales entre moros y cristianos. En la frontera ultramarina con el vecino pa\u00eds de Marruecos, se encuentran nueve islas que conforman los puntos de soberan\u00eda espa\u00f1ola en la costa norte de \u00c1frica y tenemos <strong>la frontera m\u00e1s peque\u00f1a del mundo<\/strong>.<\/p>\n<h2>El Pe\u00f1\u00f3n de V\u00e9lez de la Gomera: la frontera m\u00e1s peque\u00f1a del mundo<\/h2>\n<p>La expansi\u00f3n musulmana gener\u00f3 una era de conflictos entre moros y cristianos que se extendi\u00f3 entre el siglo VIII y el XVI, concluyendo con la Toma de Granada en 1492. Entonces el Imperio Espa\u00f1ol se expandi\u00f3 por el Mar Mediterr\u00e1neo estableciendo defensas en numerosas islas estrat\u00e9gicas, algunas de las cuales han despertado<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-islas-perdidas-pacifico\/9025\/\"> recientes reclamos de soberan\u00eda espa\u00f1ola<\/a> hasta la actualidad.<\/p>\n<p>A principios del siglo XX los conflictos entre las colonias francesas y espa\u00f1olas y la resistencia local en el norte de \u00c1frica llevaron al establecimiento de los protectorados. Se delimit\u00f3 el \u00e1rea de influencia espa\u00f1ola sobre Marruecos usando como referencia<strong> los archipi\u00e9lagos de Alhucema y Chafarinas<\/strong>, entre las ciudades de Ceuta y Melilla en la costa marroqu\u00ed, que se mantienen hasta hoy.<\/p>\n<p>El Pe\u00f1\u00f3n de V\u00e9lez de la Gomera es una formaci\u00f3n entre estas listas consideradas puntos de soberan\u00eda sobre la frontera ultramarina en la costa de Marruecos. Se trata de una masa de tierra de apenas <strong>19 kil\u00f3metros cuadrados con 100 metros en su punto m\u00e1s ancho y 15 metros en el m\u00e1s estrecho<\/strong>. En 1930 se produjo un importante terremoto que form\u00f3 un istmo, uniendo el Pe\u00f1\u00f3n a la costa marroqu\u00ed.<\/p>\n<h2>Fuente de conflictos: una peque\u00f1a \u00abroca en el mar\u00bb por la que todos se pelean<\/h2>\n<p>Aunque el Pe\u00f1\u00f3n de V\u00e9lez de la Gomera pertenece a Espa\u00f1a desde 1564 y la soberan\u00eda espa\u00f1ola est\u00e1 clara desde el Tratado de Utrech, firmado en 1713, este diminuto punto fronterizo sigue dando lugar a<strong> conflictos y reclamaciones hasta tiempos tan recientes como 2012<\/strong>. Ese a\u00f1o ciudadanos de Ceuta y Melilla subieron al pe\u00f1\u00f3n y plantaron banderas nacionalistas pero prevaleci\u00f3 la diplomacia.<\/p>\n<p>A lo largo de los siglos se sucedieron invasiones de piratas berberiscos que llegaron a ocupar el Pe\u00f1\u00f3n durante breves periodos en los que aprovecharon el lugar como refugio y base para atacar naves comerciantes que atravesaban el Mediterr\u00e1neo. Esto llev\u00f3 a que las autoridades espa\u00f1olas reforzaran las defensas y establecieran comerciantes y artesanos para mantener un control m\u00e1s efectivo.<\/p>\n<p>lleg\u00f3 a tener una poblaci\u00f3n de 400 personas entre personal militar, administrativo y civil, aunque <strong>en la actualidad s\u00f3lo habitan entre 10 y 20 personas<\/strong> que desempe\u00f1an funciones militares y se ocupan de las gestiones del punto de frontera ultramarina.<\/p>\n<h2>\u00bfTe gustar\u00eda conocer la frontera m\u00e1s peque\u00f1a del mundo y su fascinante historia?<\/h2>\n<p>Esta diminuta formaci\u00f3n rocosa, que tiene la fama de ser la frontera m\u00e1s peque\u00f1a del mundo, sigue siendo un punto de gran valor estrat\u00e9gico para Espa\u00f1a y un enclave fundamental para mantener la presencia soberana en la costa norte de Marruecos. Esto convierte al Pe\u00f1\u00f3n de V\u00e9lez de la Gomera en un tema sensible para las relaciones internacionales de ambos pa\u00edses.<\/p>\n<p>Actualmente <strong>hay varias agencias que ofrecen excursiones al Pe\u00f1\u00f3n <\/strong>para recorrer el peque\u00f1o territorio y las instalaciones defensivas que incluyen estructuras que fueron erigidas durante los largos siglos de conflictos y disputas territoriales.<\/p>\n<h2>\u00bfEuropeos o africanos? Una larga historia donde las identidades se confunden<\/h2>\n<p>La historia de las relaciones de Espa\u00f1a y Marruecos es larga y convulsa, llena de idas y venidas. El Pe\u00f1\u00f3n de V\u00e9lez de la Gomera no es el \u00fanico punto de conflicto entre ambas naciones soberanas. Entre los habitantes de las Islas Canarias existe hasta hoy <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-perdido-comunidad-autonoma\/9020\/\">una discusi\u00f3n sobre si las Islas Canarias son africanas o europeas<\/a>, un conflicto que divide la identidad cultural y el sentido de pertenencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espa\u00f1a es una tierra que abunda en historias y contrastes, especialmente all\u00ed donde se produjeron los choques culturales entre moros &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Espa\u00f1a tiene la frontera m\u00e1s peque\u00f1a del mundo, pero nos la quieren quitar: riesgo de colapso en 2024 por este pa\u00eds\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/frontera-mas-pequena-del-mundo\/9525\/#more-9525\" aria-label=\"Leer m\u00e1s sobre Espa\u00f1a tiene la frontera m\u00e1s peque\u00f1a del mundo, pero nos la quieren quitar: riesgo de colapso en 2024 por este pa\u00eds\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":9528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-9525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=9525"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/9528"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=9525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=9525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=9525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}