{"id":9949,"date":"2024-08-27T14:30:16","date_gmt":"2024-08-27T12:30:16","guid":{"rendered":"https:\/\/www.ecoticias.com\/hoyeco\/?p=9949"},"modified":"2024-08-27T14:30:16","modified_gmt":"2024-08-27T12:30:16","slug":"hidrogeno-emisiones-ciclo-de-vida","status":"publish","type":"post","link":"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-emisiones-ciclo-de-vida\/9949\/","title":{"rendered":"Al descubierto la estafa mundial del hidr\u00f3geno: el efecto irreversible que ha provocado en el planeta"},"content":{"rendered":"<p>La Uni\u00f3n Europea ha encumbrado al hidr\u00f3geno verde como el vector energ\u00e9tico del futuro, tanto como materia prima o para utilizar de combustible<a href=\"https:\/\/www.ecoticias.com\/hoyeco\/toyota-hidrogeno-coca-cola-camiones\/9757\/\">, tal como est\u00e1 utilizando en este caso,<\/a> y ser\u00e1 el protagonista de la transici\u00f3n efectiva hacia fuentes de energ\u00eda cero emisiones de carbono. Sin embargo<strong>, un estudio reciente pone en jaque estas creencias, evaluando la huella en toda la cadena de valor.<\/strong><\/p>\n<h2>Un reciente estudio pone en jaque las creencias de la UE con respecto al hidr\u00f3geno verde<\/h2>\n<p>El \u00f3rgano de m\u00e1xima autoridad europea ha establecido como fecha l\u00edmite al a\u00f1o 2030 para la producci\u00f3n de 10 millones de toneladas de hidr\u00f3geno verde y la importaci\u00f3n de otra cantidad similar para abastecer el consumo del continente y reducir al m\u00ednimo la dependencia de los f\u00f3siles.<\/p>\n<p>No obstante, ante la obstinada e irrefutable teor\u00eda, un profesor de la Universidad de Radboud y la Universidad Tecnol\u00f3gica de Eindhoven, Kiane de Kleijne, se dedic\u00f3 a estudiar y <strong>medir las emisiones de carbono y gases de efecto invernadero derivadas de la producci\u00f3n y el transporte del hidr\u00f3geno.<\/strong><\/p>\n<p>Seg\u00fan el informe publicado en la revista Nature Energy, las evaluaciones que comprenden todo el ciclo de vida del gas renovable podr\u00edan resultar decepcionantes para aquellos que lo postulan como la \u00fanica salida viable y limpia para la transici\u00f3n energ\u00e9tica.<\/p>\n<h2>Las cifras de la investigaci\u00f3n que podr\u00eda desmitificar la inocuidad del hidr\u00f3geno verde<\/h2>\n<p>La investigaci\u00f3n llevada a cabo por de Kleijne comprendi\u00f3 las mediciones de gases de efecto invernadero de m\u00e1s de 1000 proyectos de hidr\u00f3geno verde puestos en marcha, incluyendo las emisiones durante la producci\u00f3n y el transporte.<\/p>\n<p>Las conclusiones fueron contundentes y confirman que la energ\u00eda que se obtiene por la descomposici\u00f3n de los elementos del agua mediante electr\u00f3lisis <strong>es realmente renovable cuando se utiliza tecnolog\u00eda verde para su producci\u00f3n y se realiza a nivel local.<\/strong><\/p>\n<p>Es decir que el hidr\u00f3geno verde es efectivamente la energ\u00eda del futuro sin emisiones en tanto que, durante su fabricaci\u00f3n se utilice electricidad proveniente de estructuras solares o e\u00f3licas y se reduzca al m\u00ednimo el trayecto del transporte.<\/p>\n<h2>Las condiciones de producci\u00f3n y transporte del hidr\u00f3geno verde intervienen en su capacidad cero emisiones<\/h2>\n<p>El profesor que confirma la inocuidad del hidr\u00f3geno verde en proyectos donde la producci\u00f3n se lleva a cabo por energ\u00eda renovable y de forma local, subraya <strong>la tendencia a elevar las emisiones cuando valora todo el ciclo de vida de creaci\u00f3n.<\/strong><\/p>\n<p>Por un lado, de Kleijne sostiene que la energ\u00eda proveniente del sol es mejor que la e\u00f3lica teniendo en cuenta las emisiones de carbono generadas en la fabricaci\u00f3n de aerogeneradores y la industria del acero para los electrolizadores.<\/p>\n<p>Adicionalmente, coloca su atenci\u00f3n en los m\u00e9todos de transporte de la energ\u00eda, <strong>aumentando el riesgo de fuga y el nivel de la huella de carbono a mayor distancia recorrida.<\/strong> En estos casos, postula al formato l\u00edquido como m\u00e1s viable para mayores trayectos, pero insiste en la fabricaci\u00f3n local.<\/p>\n<h2>El gran potencial del hidr\u00f3geno verde proveniente de energ\u00edas renovables y de producci\u00f3n local<\/h2>\n<p>El informe es un llamado de atenci\u00f3n para quienes no consideran toda la cadena de vida de la fabricaci\u00f3n de energ\u00eda y para evaluar la conveniencia de instalaci\u00f3n de industrias tan alejadas de la regi\u00f3n de origen.<\/p>\n<p>Tal es el caso que se produce en zonas como Brasil o \u00c1frica donde se fabrica hidr\u00f3geno verde a partir de la excelente capacidad de exposici\u00f3n al sol y menores vientos. Sin embargo<strong>, el traslado a Europa implica un aumento de emisiones y de fugas durante el transporte que hasta hoy no eran consideradas<\/strong>.<\/p>\n<p>A partir de ahora, las evaluaciones de viabilidad de instalaci\u00f3n y fabricaci\u00f3n del hidr\u00f3geno verde podr\u00e1n certificarlo como la energ\u00eda limpia y renovable que es y convertirse en el recurso m\u00e1s eficiente para el cambio clim\u00e1tico en los pr\u00f3ximos a\u00f1os. Aqu\u00ed podr\u00e1s conocer <a href=\"https:\/\/www.ecoticias.com\/hoyeco\/espana-biometano-75-gwh-transporte\/9761\/\">un proyecto que utiliza hidr\u00f3geno verde para el transporte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Europea ha encumbrado al hidr\u00f3geno verde como el vector energ\u00e9tico del futuro, tanto como materia prima o para &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Al descubierto la estafa mundial del hidr\u00f3geno: el efecto irreversible que ha provocado en el planeta\" class=\"read-more button\" href=\"https:\/\/www.ecoticias.com\/hoyeco\/hidrogeno-emisiones-ciclo-de-vida\/9949\/#more-9949\" aria-label=\"Leer m\u00e1s sobre Al descubierto la estafa mundial del hidr\u00f3geno: el efecto irreversible que ha provocado en el planeta\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":9950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/comments?post=9949"}],"version-history":[{"count":0,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/posts\/9949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media\/9950"}],"wp:attachment":[{"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/media?parent=9949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/categories?post=9949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoticias.com\/hoyeco\/wp-json\/wp\/v2\/tags?post=9949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}